{"id":3694,"date":"2025-10-25T12:30:40","date_gmt":"2025-10-25T10:30:40","guid":{"rendered":"https:\/\/www.kmws.de\/sauerland\/?p=3694"},"modified":"2025-10-25T12:30:40","modified_gmt":"2025-10-25T10:30:40","slug":"ausbeute-aus-essen","status":"publish","type":"post","link":"http:\/\/www.kmws.de\/sauerland\/ausbeute-aus-essen","title":{"rendered":"Ausbeute aus Essen"},"content":{"rendered":"<p><strong>Roy<\/strong>, unser Mann f\u00fcr die Spiele, ist von der <strong>SPIEL<\/strong><a href=\"http:\/\/www.kmws.de\/sauerland\/wp-content\/uploads\/2025\/10\/qrcode.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3696 alignright\" src=\"http:\/\/www.kmws.de\/sauerland\/wp-content\/uploads\/2025\/10\/qrcode-300x300.png\" alt=\"\" width=\"150\" height=\"150\" srcset=\"http:\/\/www.kmws.de\/sauerland\/wp-content\/uploads\/2025\/10\/qrcode-300x300.png 300w, http:\/\/www.kmws.de\/sauerland\/wp-content\/uploads\/2025\/10\/qrcode-150x150.png 150w, http:\/\/www.kmws.de\/sauerland\/wp-content\/uploads\/2025\/10\/qrcode.png 328w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a> in Essen zur\u00fcck und hat an die 60 neue Spiele f\u00fcr den Spieletreff mitgebracht. Er wird sie in den n\u00e4chsten Tagen nach und nach in unsere Geeklist einpflegen, auf die Ihr jetzt auch per QR Code zugreifen k\u00f6nnt: https:\/\/boardgamegeek.com\/geeklist\/364902\/willingen-2025<br \/>\nUnd nat\u00fcrlich hoffen wir auf weitere Verlagspakete. Bisher sind diese eingetroffen von der AMIGO Spiel + Freizeit, Schmidt Spiele, Hutter Trade und HeidelB\u00c4R.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roy, unser Mann f\u00fcr die Spiele, ist von der SPIEL in Essen zur\u00fcck und hat an die 60 neue Spiele f\u00fcr den Spieletreff mitgebracht. Er wird sie in den n\u00e4chsten Tagen nach und nach in unsere Geeklist einpflegen, auf die &hellip; <a href=\"http:\/\/www.kmws.de\/sauerland\/ausbeute-aus-essen\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,4],"tags":[],"_links":{"self":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3694"}],"collection":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/comments?post=3694"}],"version-history":[{"count":4,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3694\/revisions"}],"predecessor-version":[{"id":3699,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3694\/revisions\/3699"}],"wp:attachment":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/media?parent=3694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/categories?post=3694"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/tags?post=3694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}