{"id":3425,"date":"2024-10-02T14:24:03","date_gmt":"2024-10-02T12:24:03","guid":{"rendered":"https:\/\/www.kmws.de\/sauerland\/?p=3425"},"modified":"2024-10-02T14:24:03","modified_gmt":"2024-10-02T12:24:03","slug":"neue-spiele-i","status":"publish","type":"post","link":"http:\/\/www.kmws.de\/sauerland\/neue-spiele-i","title":{"rendered":"Neue Spiele (I)"},"content":{"rendered":"<p>Der Pokal f\u00fcr die schnellste Lieferung geht in diesem Jahr an <strong>Hutter Trade<\/strong>, die uns bereits am 9. September die folgenden Spiele von HUCH! f\u00fcr den Spieletreff geliefert haben:<\/p>\n<p>Floral<br \/>\nGalerie der K\u00fcnste<br \/>\nKreisel durch die Welt<br \/>\nTouch it \u2013 Animals<\/p>\n<p>Au\u00dferdem wurden uns noch die beiden Spiele Knarr und Stichwahl avisiert, die aktuell nicht lieferbar waren. Wir bedanken uns recht herzlich!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Pokal f\u00fcr die schnellste Lieferung geht in diesem Jahr an Hutter Trade, die uns bereits am 9. September die folgenden Spiele von HUCH! f\u00fcr den Spieletreff geliefert haben: Floral Galerie der K\u00fcnste Kreisel durch die Welt Touch it \u2013 &hellip; <a href=\"http:\/\/www.kmws.de\/sauerland\/neue-spiele-i\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,4],"tags":[],"_links":{"self":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3425"}],"collection":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/comments?post=3425"}],"version-history":[{"count":2,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3425\/revisions"}],"predecessor-version":[{"id":3427,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3425\/revisions\/3427"}],"wp:attachment":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/media?parent=3425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/categories?post=3425"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/tags?post=3425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}