{"id":3229,"date":"2023-10-09T09:23:52","date_gmt":"2023-10-09T07:23:52","guid":{"rendered":"http:\/\/www.kmws.de\/sauerland\/?p=3229"},"modified":"2023-10-09T11:07:37","modified_gmt":"2023-10-09T09:07:37","slug":"nach-der-spiel-ist-vor-dem-spieletreff","status":"publish","type":"post","link":"http:\/\/www.kmws.de\/sauerland\/nach-der-spiel-ist-vor-dem-spieletreff","title":{"rendered":"Nach der SPIEL ist vor dem Spieletreff"},"content":{"rendered":"<p>Roy, unser flei\u00dfiger Akquisiteur, war zwei Tage lang auf der <strong>SPIEL in Essen<\/strong> und hat Aussteller um Spiele f\u00fcr den diesj\u00e4hrigen Spieletreff gebeten. Erfreulicherweise waren viele bereit zu spenden, und so konnte er fast 90 gro\u00dfe und kleine Schachteln ins Auto laden, nicht nur Neuheiten, auch manchen \u00e4lteren Titel. Hier die alphabetische Liste:<\/p>\n<p>1% One Percent (Iconiq Studios)<br \/>\nArschlochkind (Kampfhummel Spiele)<br \/>\nAt the Office (Trefl)<br \/>\nIt&#8217;s a Balloon!? (PD Verlag)<br \/>\nBattle of Midway (Bored Games)<br \/>\nBier Pioniere (Spielefaible)<br \/>\nBlack Friday (2F-Spiele)<br \/>\nBruxelles 1893 (Geek Attitude Games)<br \/>\nBruxelles 1897 (Geek Attitude Games)<br \/>\nButaBabel (Homosapiens Lab)<br \/>\nBy the Book (HCM Kinzel)<br \/>\nCarry me Plz (Homosapiens Lab)<br \/>\nCascadia: Landmarks (Alderac Entertainment Group (AEG))<br \/>\nCGT: Card Game Traders (Da\u017ebog Games)<br \/>\nLeonardo da Vinci&#8217;s Codex Leicester (Dice Tree games)<br \/>\nColor Flush (HCM Kinzel)<br \/>\nCombo Fighter (2x) (Plotmaker Games)<br \/>\nCrimson Company (Crimson Company)<br \/>\nDeep Dive (Alderac Entertainment Group (AEG))<br \/>\nDie Verr\u00e4ter (Goliath)<br \/>\nDinosaur Island Rawr &#8217;n Write (Pandasaurus Games)<br \/>\nDog Lovers (Alderac Entertainment Group (AEG))<br \/>\nDOUC Kids (Douc in Danger)<br \/>\nDragon Ranch (Azao Games)<br \/>\nDragon Ranch (Teasy Game) (Azao Games)<br \/>\nDreamscape (Sylex Edition)<br \/>\nDschungelgedr\u00e4ngel (frechverlag)<br \/>\nDubious (Arcane Wonders)<br \/>\nDungeon Twister: The Card Game (Ludically)<br \/>\nEnsemble (Ares Games)<br \/>\nEuropean Union: The Board Game (Big Fun Games)<br \/>\nFit to Print (Alderac Entertainment Group (AEG))<br \/>\nFive Peaks (Trefl)<br \/>\nFlip Hop (Teasy Game) (Azao Games)<br \/>\nFreaky Frogs From Outaspace (2F-Spiele)<br \/>\nFTW?! (2F-Spiele)<br \/>\nGame Night in a Can (Goliath)<br \/>\nGangsters (Ares)<br \/>\nGAP (Arcane Wonders)<br \/>\nGay Sauna: The Board Game (ReRoll Works)<br \/>\nGumminis (HCM Kinzel)<br \/>\nHard to Get (Gameplay Publishing)<br \/>\nHigh Noon (High Noon Game)<br \/>\nHow DARE you? (Alion Games)<br \/>\nKampf gegen das Spiessertum (Kampfhummel Spiele)<br \/>\nKutna Hora: Stadt des Silbers (CGE)<br \/>\nLiving Planet (Ludically)<br \/>\nLucky First Incense (Lilai Lilai)<br \/>\nMachi Koro 5th Aniversary Ed. (Pandasaurus Games)<br \/>\nMateria Prima (Peacock Tabletops)<br \/>\nMind Bug (2x) (Nerdlab)<br \/>\nMobile Markets: A Smartphone Inc. Game (Arcane Wonders)<br \/>\nMonster Hide and Seek (Homosapiens Lab)<br \/>\nNext Station Tokyo (HCM Kinzel)<br \/>\nNuklear (Kampfhummel Spiele)<br \/>\nNumber Drop (Alderac Entertainment Group (AEG))<br \/>\nOne Card Dungeon (Little Rocket Games)<br \/>\nOvercrowd (Ars Ludi)<br \/>\nPictures (PD Verlag)<br \/>\nPictures USA Erweiterung (PD Verlag)<br \/>\nPitch Fleet (Two Plus)<br \/>\nPoint City (Alderac Entertainment Group (AEG))<br \/>\nPong Party (Goliath)<br \/>\nPrinting Press (Granna)<br \/>\nQuicksand (Horrible Guild)<br \/>\nQuirky Quarks (Quirky Quarks)<br \/>\nRUN (Fower Games)<br \/>\nS\u00e1r\u00e9n\u00e1 (2x) (Ludically)<br \/>\nShake that City (Alderac Entertainment Group (AEG))<br \/>\nSimilo (Horrible Guild)<br \/>\nSneaky Snakes (Sneaky Snakes Cards)<br \/>\nSoda (Teasy Games) (Azao Games)<br \/>\nSpeed Letters (HCM Kinzel)<br \/>\nSpy Guy Deutschland (Trefl)<br \/>\nStory Teller (TWOPLUS Games)<br \/>\nSunrise Lane (Horrible Guild)<br \/>\nSweet Mess: Pastry Competition (Pika Games)<br \/>\nTension (HCM Kinzel)<br \/>\nTerraforming Mars: The Dice Game (Fryxgames)<br \/>\nThat Old Wallpaper (Alderac Entertainment Group (AEG))<br \/>\nThe Dracula Game (Roovi)<br \/>\nThe Rich and the Good (Ares Games)<br \/>\nUND1C1. (DM Giochi SRLS)<br \/>\nUnrest (Pandasaurus Games)<br \/>\nVerplant &amp; Zugestellt (frechverlag)<br \/>\nVIP RIP (Nice Game Publishing)<br \/>\nWortwiesel (frechverlag)<br \/>\nWuzzled! (Iconiq Studios)<br \/>\nZoollywood Polar Quest (Blue Piper)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roy, unser flei\u00dfiger Akquisiteur, war zwei Tage lang auf der SPIEL in Essen und hat Aussteller um Spiele f\u00fcr den diesj\u00e4hrigen Spieletreff gebeten. Erfreulicherweise waren viele bereit zu spenden, und so konnte er fast 90 gro\u00dfe und kleine Schachteln ins &hellip; <a href=\"http:\/\/www.kmws.de\/sauerland\/nach-der-spiel-ist-vor-dem-spieletreff\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,4],"tags":[],"_links":{"self":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3229"}],"collection":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/comments?post=3229"}],"version-history":[{"count":3,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3229\/revisions"}],"predecessor-version":[{"id":3233,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/3229\/revisions\/3233"}],"wp:attachment":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/media?parent=3229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/categories?post=3229"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/tags?post=3229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}