{"id":19,"date":"2015-10-16T09:56:11","date_gmt":"2015-10-16T07:56:11","guid":{"rendered":"http:\/\/www.kmws.de\/sauerland\/?p=19"},"modified":"2015-11-12T19:07:09","modified_gmt":"2015-11-12T18:07:09","slug":"ein-langer-aber-relativ-wichtiger-post","status":"publish","type":"post","link":"http:\/\/www.kmws.de\/sauerland\/ein-langer-aber-relativ-wichtiger-post","title":{"rendered":"Ein langer, aber relativ wichtiger Post!"},"content":{"rendered":"<p>Hallo zusammen,<\/p>\n<p>in diesem Jahr habe ich erstmalig die Verantwortung f\u00fcr die Spiele bzw. deren Beschaffung von Knut-Michael Wolf \u00fcbernommen. Knut hat im Hintergrund sehr hilfreich mitgewirkt und ein ordentlich gro\u00dfer Dank geht an ihn. Ich war nur das freundliche Gesicht auf der Messe.<\/p>\n<p>Ich melde mich, weil sich ein paar Dinge in diesem Jahr \u00e4ndern werden.<\/p>\n<p><strong>SPIELEAUSLEIHE<\/strong><br \/>\nAufgrund der unerfreulichen Vorkommnisse im letzten Jahr wird es (zumindest ist das der aktuelle Stand) eine Spieleausleihe geben.<\/p>\n<p><strong>MEHR SPIELE<\/strong><br \/>\nNachdem ich etwas mehr Zeit auf der Messe hatte, und \u00fcber eine angeborene Unverfrorenheit verf\u00fcge, habe ich neben den bekannten deutschen Verlagen und Vertrieben auch diverse internationale Kleinverlage um Spiele gebeten. Mit erfreulicher Resonanz.<\/p>\n<p><strong>FOTOS<\/strong><br \/>\nAllerdings haben mich die meisten dieser kleinen Verlage darum gebeten unbedingt Bilder zu machen wenn ihre Spiele gespielt werden. Und da kommt Ihr hoffentlich ins Boot. Sprich wenn Ihr euch ein Spiel holt und es spielt, nehmt euch doch euer Smartphone und macht ein Bild. Das ganze k\u00f6nnt Ihr dann entweder per Whattsapp, Hangouts oder am besten direkt per E-Mail an mich senden. Die entsprechenden Kontaktdaten werde ich dann im Hotel bekannt geben.<br \/>\nJetzt kann der ein oder andere sagen. was k\u00fcmmert mich die Bitte, ich mach das alles so wie immer. Fotos kann sich der Herr Burger abschminken. Das w\u00e4re in so fern betr\u00fcblich, als ich dann im kommenden Jahr bei den kleinen Verlagen nicht mehr vorstellig zu werden br\u00e4uchte und es dann auch nicht tun w\u00fcrde. Wenn ich ordentlich Fotos bekomme, w\u00fcrde ich versuchen das mit den internationalen Verlagen 2016 noch zu intensivieren.<\/p>\n<p><strong>EVALUATION<\/strong><br \/>\nAuch hier w\u00fcrden wir ein wenig mehr machen wollen, um den Verlagen einen kleinen Mehrwert zu bieten. Wir sind am \u00fcberlegen das bisherige Notensystem, um die Felder Spieleranzahl und Kommentar zu erweitern. Auch hier gilt &#8211; etwas eingeschr\u00e4nkter &#8211; das was ich zu den Fotos gesagt habe. Auch hier hilft den Verlagen eine rege Beteiligung. Und uns in der Summe dann nat\u00fcrlich auch.<\/p>\n<p><strong>SPIELELISTE<\/strong> (momentan nur int. Kleinverlage)<br \/>\nHier fehlen noch ca. 10 Spiele, die sind schon im Hotel. Diese werde ich noch nachliefern.<br \/>\nLords of War (Black Box Games)<br \/>\nGame of Trains (Brain Games)<br \/>\nOm Nom Nom (Brain Games)<br \/>\nDig Mars (Brain Games)<br \/>\nTop Face (Buzzy Gamex)<br \/>\nCrazy Bullets (Desyllas)<br \/>\nSing it! (Desyllas)<br \/>\nOMG (Desyllas)<br \/>\nAmphipolis (Desyllas)<br \/>\nMess Machine (Desyllas)<br \/>\nOath of the Brotherhood (Desyllas)<br \/>\nGigamon (Elemon Games)<br \/>\nTokaido (Fun Forge)<br \/>\nTaverna (Geek Attitude Games)<br \/>\nWaggle Dance (Grublin)<br \/>\nCornish Smuggler (Grublin)<br \/>\nRunes &amp; Ruin (Homosapiens Lab)<br \/>\nFalling Coin (Homosapiens Lab)<br \/>\nFlowering Snail (Homosapiens Lab)<br \/>\nDesign Town (Homosapiens Lab)<br \/>\nTanto Cuore Oktoberfest (Japanime Games)<br \/>\nIce in the Sky (Jeux Opla)<br \/>\nGuns and Steel (Moaideas Game Design)<br \/>\nJoraku (Moaideas Game Design)<br \/>\nAnimals Frightening Night (Mozi Games)<br \/>\nCha dango (Mozi Games)<br \/>\nBlack Sheep and White Sheep (Mozi Games)<br \/>\nOrracoke (Mozi Games)<br \/>\nThe Magnates (Phalanx)<br \/>\nRace to the Rhine (Phalanx)<br \/>\nFun Farm (Post Scriptum )<br \/>\nBrick Party (Post Scriptum )<br \/>\nAlien Wars (Superlude)<br \/>\nKenjin (Superlude)<br \/>\nLutece (Superlude)<br \/>\nShips (Treefrog Games)<br \/>\nMoongha Invaders (Treefrog Games)<\/p>\n<p>So und nun noch einmal durch schnaufen: Klassiker wie das R\u00e4tsel und die Verlosungen wird es nat\u00fcrlich auch weiterhin geben. Nicht alles wird anders.<\/p>\n<p>Gr\u00fc\u00dfe<br \/>\nRoy<\/p>\n<p>PS: Auf der <a href=\"https:\/\/www.facebook.com\/groups\/107311656001787\/\">Facebook-Seite zum Spieletreff<\/a>\u00a0finden sich noch erg\u00e4nzende Kommentare dazu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hallo zusammen, in diesem Jahr habe ich erstmalig die Verantwortung f\u00fcr die Spiele bzw. deren Beschaffung von Knut-Michael Wolf \u00fcbernommen. Knut hat im Hintergrund sehr hilfreich mitgewirkt und ein ordentlich gro\u00dfer Dank geht an ihn. Ich war nur das freundliche &hellip; <a href=\"http:\/\/www.kmws.de\/sauerland\/ein-langer-aber-relativ-wichtiger-post\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,4],"tags":[],"_links":{"self":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/19"}],"collection":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":3,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/19\/revisions"}],"predecessor-version":[{"id":22,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/19\/revisions\/22"}],"wp:attachment":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/media?parent=19"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/categories?post=19"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/tags?post=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}