{"id":1212,"date":"2017-11-14T14:30:29","date_gmt":"2017-11-14T13:30:29","guid":{"rendered":"http:\/\/www.kmws.de\/sauerland\/?p=1212"},"modified":"2017-11-14T14:30:29","modified_gmt":"2017-11-14T13:30:29","slug":"neue-spiele-fuer-2017-vii","status":"publish","type":"post","link":"http:\/\/www.kmws.de\/sauerland\/neue-spiele-fuer-2017-vii","title":{"rendered":"Neue Spiele f\u00fcr 2017 (VII)"},"content":{"rendered":"<p>Auch von <strong>Kosmos<\/strong> sind inzwischen Spiele im Hotel eingetroffen, welche genau wissen wir allerdings nicht, da uns bislang kein Lieferschein vorliegt. Wir tippen mal auf mindestens folgende Titel:<\/p>\n<p>Das Fundament der Ewigkeit<br \/>\nHanamikoji<br \/>\nHolmes<br \/>\nKodama: Die Baumgeister<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch von Kosmos sind inzwischen Spiele im Hotel eingetroffen, welche genau wissen wir allerdings nicht, da uns bislang kein Lieferschein vorliegt. Wir tippen mal auf mindestens folgende Titel: Das Fundament der Ewigkeit Hanamikoji Holmes Kodama: Die Baumgeister<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/1212"}],"collection":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/comments?post=1212"}],"version-history":[{"count":1,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/1212\/revisions"}],"predecessor-version":[{"id":1213,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/posts\/1212\/revisions\/1213"}],"wp:attachment":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/media?parent=1212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/categories?post=1212"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/tags?post=1212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}