{"id":3203,"date":"2022-11-28T15:47:24","date_gmt":"2022-11-28T14:47:24","guid":{"rendered":"http:\/\/www.kmws.de\/sauerland\/spieltische-2022"},"modified":"2022-11-28T15:56:19","modified_gmt":"2022-11-28T14:56:19","slug":"spieltische-2022","status":"publish","type":"page","link":"http:\/\/www.kmws.de\/sauerland\/spieltische-2022","title":{"rendered":"Spieltische 2022"},"content":{"rendered":"<p>Hier eine Auswahl der Spiele, die beim 37. Spieletreff auf die Tische kamen, unsortiert, manche auch mehrfach und in verschiedenen Stadien der Partie abgelichtet. Die Handy-Kamera draufgehalten hat KMW.<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>Hier eine Auswahl der Spiele, die beim 37. Spieletreff auf die Tische kamen, unsortiert, manche auch mehrfach und in verschiedenen Stadien der Partie abgelichtet. Die Handy-Kamera draufgehalten hat KMW. &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"_links":{"self":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/pages\/3203"}],"collection":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/comments?post=3203"}],"version-history":[{"count":4,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/pages\/3203\/revisions"}],"predecessor-version":[{"id":3207,"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/pages\/3203\/revisions\/3207"}],"wp:attachment":[{"href":"http:\/\/www.kmws.de\/sauerland\/wp-json\/wp\/v2\/media?parent=3203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}